{"id":545,"date":"2013-03-28T11:40:31","date_gmt":"2013-03-28T14:40:31","guid":{"rendered":"http:\/\/www.renatoalves.com.br\/blog\/?p=545"},"modified":"2021-10-14T15:14:39","modified_gmt":"2021-10-14T18:14:39","slug":"importancia-do-revisor","status":"publish","type":"post","link":"https:\/\/renatoalves.com.br\/blog\/importancia-do-revisor\/","title":{"rendered":"A import\u00e2ncia do Revisor"},"content":{"rendered":"<p style=\"text-align: justify;\">&#8220;HJE \u00c9 UN DIA INSPECIAL!&#8221;. Dizem que o revisor \u00e9 um ca\u00e7ador de distra\u00e7\u00f5es. Na verdade \u00e9 um profissional altamente qualificado que trabalha nos bastidores de jornais e editoras. \u00c9 ele que garante a qualidade dos textos liter\u00e1rios e jornal\u00edsticos que saboreamos todos os dias.<\/p>\n<h2>Para voc\u00ea qual a\u00a0import\u00e2ncia do Revisor?<\/h2>\n<p style=\"text-align: justify;\">\u00c9 uma esp\u00e9cie de Coaching Ortogr\u00e1fico que todos n\u00f3s um dia dever\u00edamos experimentar.<\/p>\n<p style=\"text-align: justify;\">Sou um cara de sorte. Se \u00e9 verdade que Deus coloca as pessoas certas em nossos caminhos, ent\u00e3o fui privilegiado ao ter a sorte de trabalhar por mais de 10 anos com um revisor profissional, Sr. Innocente Chiaradia. Ele foi meu chefe e hoje \u00e9 um grande amigo ao qual devo muito de minha qualidade como autor.<\/p>\n<p style=\"text-align: justify;\">Lembro-me das minhas primeiras aventuras no exerc\u00edcio da escrita. Eu entrava em sua sala com um calhama\u00e7o de papel pedindo uma revis\u00e3o e dias depois ele me devolvia recheados de anota\u00e7\u00f5es marcadas com o vermelho t\u00edpico das canetas Bic.<\/p>\n<p style=\"text-align: center;\">[inf_infusionsoft_inline optin_id=optin_1]<\/p>\n<p style=\"text-align: justify;\">Ele fazia quest\u00e3o de, calmamente, me explicar cada das suas observa\u00e7\u00f5es, p\u00e1gina por p\u00e1gina. Confesso que naquelas horas minha vontade era de cavar um buraco e me enfiar dentro.<\/p>\n<p style=\"text-align: justify;\">O \u201cseu Innocente\u201d, como gostava de chamar, era gentil, e me dizia com toda delicadeza que todos aqueles erros eram meros \u201cerros de digita\u00e7\u00e3o&#8221; atribu\u00eddos a esses \u201cteclados pequenos, modernos&#8230;\u201d.<\/p>\n<p style=\"text-align: justify;\">Ele sutilmente me iludia para tirar o foco daquilo que na verdade n\u00e3o passava de uma grande &#8220;limita\u00e7\u00e3o gramatical&#8221; que emperrava meu c\u00e9rebro.<\/p>\n<p style=\"text-align: justify;\">Passaram-se os anos e evidentemente eu soube aprender com meus erros. Hoje sou autor de oito livros que somados j\u00e1 ultrapassaram 500 mil c\u00f3pias. Um dos \u00faltimos lan\u00e7amentos, <a href=\"http:\/\/www.humanoeditora.com.br\/faca-seu-cerebro-trabalhar-para-voce-p35\" target=\"_blank\" rel=\"noopener\">Fa\u00e7a seu C\u00e9rebro Trabalhar para Voc\u00ea<\/a> &#8211; Editora Gente \u00e9 o \u00e1pice da minha carreira de escritor.<\/p>\n<p style=\"text-align: justify;\">Ele trouxe um Renato Alves muito mais preparado, capaz de fazer um texto bem mais envolvente, objetivo, criativo e did\u00e1tico.<\/p>\n<p style=\"text-align: justify;\">At\u00e9 hoje tenho recebido \u00f3timos feedbacks do novo livro e isso \u00e9 prova de que eu realmente amadureci como escritor. Mas um escritor nunca est\u00e1 totalmente formado e por isso acho que tenho muito que melhorar.<\/p>\n<p style=\"text-align: justify;\">Dizem que escritor \u00e9 como um bom vinho. Quanto mais envelhecemos, melhor ficamos&#8230;<\/p>\n<p style=\"text-align: justify;\">O conv\u00edvio e a influ\u00eancia de um bom revisor me fez pular algumas etapas. Hoje eu consigo produzir um texto, digamos, degust\u00e1veis, sem ter envelhecido tanto assim.<\/p>\n<p style=\"text-align: justify;\">Devo minha qualidade de autor ao conv\u00edvio que tive com um revisor profissional. Por isso deixo aqui meus parab\u00e9ns ao guru, coach, amigo, Sr Innocente e a todos os revisores de todos os jornais e editoras do pa\u00eds.<\/p>\n<p style=\"text-align: justify;\">28 de Mar\u00e7o, dia do Revisor.<br \/>\nParab\u00e9ns pelo seu trabalho, parab\u00e9ns pelo seu dia!<\/p>\n<p style=\"text-align: justify;\">Gostou do texto?\u00a0N\u00e3o esque\u00e7a de comentar abaixo e indicar para um amigo. Quer receber mais dicas? Curta a minha p\u00e1gina do\u00a0<a href=\"https:\/\/www.facebook.com\/RenatoAlvesOficial?utm_source=blog&amp;utm_campaign=rc_blogpost\">Facebook<\/a>\u00a0e inscreva-se no meu canal no\u00a0<a href=\"https:\/\/www.youtube.com\/user\/videosmemoria\/videos?sub_confirmation=1\">Youtube<\/a>.<\/p>\n<p style=\"text-align: justify;\">Aproveite e conhe\u00e7a o meu m\u00e9todo de leitura din\u00e2mica,\u00a0<span class=\"s1\">o curso\u00a0<a href=\"https:\/\/leiturarapida.com.br\">FastRead<\/a><\/span><span class=\"s1\">, como incentivo<\/span><span class=\"s1\">\u00a0<\/span>por acreditar tanto na efici\u00eancia do meu m\u00e9todo, al\u00e9m dos b\u00f4nus eu ainda lhe ofere\u00e7o uma garantia mais que especial.<\/p>\n<p style=\"text-align: center;\"><a href=\"\/\/renatoalves.com.br\/depoimentos.html\">\u00bb Clique Aqui\u00a0e assista alguns depoimentos de alunos do curso\u00a0\u00ab<\/a><\/p>\n<p style=\"text-align: justify;\">Se em 7 dias, depois de aplicar o m\u00e9todo, voc\u00ea\u00a0 n\u00e3o notar melhoras, eu assumo total responsabilidade e devolverei 100% do seu investimento. O que voc\u00ea acha?\u00a0<a href=\"https:\/\/leiturarapida.com.br\">Clique aqui<\/a> e comece agora mesmo a sua caminhada rumo ao seleto grupo de pessoas que conseguem ler tranquilamente mais de 50 livros por ano.<\/p>\n<p style=\"text-align: justify;\"><em><strong>Renato Alves<\/strong>\u00a0\u00e9 escritor, pesquisador e primeiro brasileiro a receber o t\u00edtulo oficial de melhor mem\u00f3ria do Brasil. Autor de um m\u00e9todo patenteado de memoriza\u00e7\u00e3o que ganhou reconhecimento nacional e j\u00e1 est\u00e1 presente em mais de 100 pa\u00edses.<\/em><\/p>\n<p><a href=\"https:\/\/leiturarapida.com.br\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-2517 size-full aligncenter\" src=\"\/\/renatoalves.com.br\/blog\/wp-content\/uploads\/2015\/02\/banner_FR.jpg\" alt=\"Curso Fast Read\" width=\"3002\" height=\"353\" srcset=\"https:\/\/renatoalves.com.br\/blog\/wp-content\/uploads\/2015\/02\/banner_FR.jpg 3002w, https:\/\/renatoalves.com.br\/blog\/wp-content\/uploads\/2015\/02\/banner_FR-300x35.jpg 300w, https:\/\/renatoalves.com.br\/blog\/wp-content\/uploads\/2015\/02\/banner_FR-768x90.jpg 768w, https:\/\/renatoalves.com.br\/blog\/wp-content\/uploads\/2015\/02\/banner_FR-1024x120.jpg 1024w\" sizes=\"(max-width: 3002px) 100vw, 3002px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dizem que revisor \u00e9 ca\u00e7ador de distra\u00e7\u00f5es. Mas na verdade \u00e9 um profissional altamente qualificado que trabalha nos bastidores de jornais e editoras. \u00c9 ele que garante a qualidade dos textos liter\u00e1rios e jornal\u00edsticos que saboreamos todos os dias. \u00c9 uma esp\u00e9cie de Coaching Ortogr\u00e1fico que todos n\u00f3s um dia dever\u00edamos experimentar. <\/p>\n","protected":false},"author":24,"featured_media":965,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[263],"tags":[],"class_list":["post-545","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-leitura-e-leitura-dinamica"],"_links":{"self":[{"href":"https:\/\/renatoalves.com.br\/blog\/wp-json\/wp\/v2\/posts\/545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/renatoalves.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/renatoalves.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/renatoalves.com.br\/blog\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/renatoalves.com.br\/blog\/wp-json\/wp\/v2\/comments?post=545"}],"version-history":[{"count":2,"href":"https:\/\/renatoalves.com.br\/blog\/wp-json\/wp\/v2\/posts\/545\/revisions"}],"predecessor-version":[{"id":7675,"href":"https:\/\/renatoalves.com.br\/blog\/wp-json\/wp\/v2\/posts\/545\/revisions\/7675"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/renatoalves.com.br\/blog\/wp-json\/wp\/v2\/media\/965"}],"wp:attachment":[{"href":"https:\/\/renatoalves.com.br\/blog\/wp-json\/wp\/v2\/media?parent=545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/renatoalves.com.br\/blog\/wp-json\/wp\/v2\/categories?post=545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/renatoalves.com.br\/blog\/wp-json\/wp\/v2\/tags?post=545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}